{"id":8890,"date":"2025-07-14T21:43:38","date_gmt":"2025-07-14T19:43:38","guid":{"rendered":"https:\/\/bicyclejack.de\/clause-de-non-responsabilite\/"},"modified":"2026-04-22T21:23:59","modified_gmt":"2026-04-22T19:23:59","slug":"clause-de-non-responsabilite","status":"publish","type":"page","link":"https:\/\/bicyclejack.de\/fr\/clause-de-non-responsabilite\/","title":{"rendered":"Clause de non-responsabilit\u00e9"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling colored-page-header\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:var(--awb-color5);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-align-content-flex-end fusion-flex-content-wrap\" style=\"max-width:1705.6px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:var(--awb-typography2-font-size);\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;DM Sans&quot;;font-style:normal;font-weight:700;margin:0;letter-spacing:var(--awb-typography2-letter-spacing);text-transform:none;font-size:1em;--fontSize:60;line-height:var(--awb-typography2-line-height);\">Clause de non-responsabilit\u00e9<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:130px;--awb-padding-bottom:130px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1705.6px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-row\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-font-size:var(--awb-typography4-font-size);--awb-line-height:1.6;--awb-letter-spacing:var(--awb-typography4-letter-spacing);--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:var(--awb-color6);--awb-text-font-family:&quot;DM Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:500;\"><p><strong>1. contenu de l&rsquo;offre en ligne<\/strong><br \/>\nL&rsquo;auteur ne garantit pas l&rsquo;actualit\u00e9, l&rsquo;exactitude, l&rsquo;exhaustivit\u00e9 ou la qualit\u00e9 des informations mises \u00e0 disposition. Toute revendication de responsabilit\u00e9 contre l&rsquo;auteur concernant des dommages mat\u00e9riels ou immat\u00e9riels caus\u00e9s par l&rsquo;utilisation ou la non-utilisation des informations pr\u00e9sent\u00e9es ou par l&rsquo;utilisation d&rsquo;informations erron\u00e9es ou incompl\u00e8tes est fondamentalement exclue, \u00e0 moins qu&rsquo;il ne soit prouv\u00e9 que l&rsquo;auteur a commis une faute intentionnelle ou une n\u00e9gligence grave.<br \/>\nToutes les offres sont sans engagement et non contractuelles. L&rsquo;auteur se r\u00e9serve express\u00e9ment le droit de modifier, de compl\u00e9ter ou de supprimer des parties de pages ou l&rsquo;ensemble de l&rsquo;offre sans avis pr\u00e9alable, ou d&rsquo;en suspendre temporairement ou d\u00e9finitivement la publication.  <\/p>\n<p><strong>2 R\u00e9f\u00e9rences et liens<\/strong><br \/>\nEn cas de r\u00e9f\u00e9rences directes ou indirectes \u00e0 des sites web \u00e9trangers (\u00ab\u00a0hyperliens\u00a0\u00bb) qui ne rel\u00e8vent pas de la responsabilit\u00e9 de l&rsquo;auteur, une obligation de responsabilit\u00e9 entrerait uniquement en vigueur dans le cas o\u00f9 l&rsquo;auteur aurait connaissance des contenus et qu&rsquo;il lui serait techniquement possible et raisonnable d&#8217;emp\u00eacher l&rsquo;utilisation en cas de contenus ill\u00e9gaux.<br \/>\nL&rsquo;auteur d\u00e9clare express\u00e9ment par la pr\u00e9sente qu&rsquo;au moment de l&rsquo;\u00e9tablissement des liens, aucun contenu ill\u00e9gal n&rsquo;\u00e9tait identifiable sur les pages \u00e0 relier. L&rsquo;auteur n&rsquo;a aucune influence sur la conception actuelle et future, les contenus ou la paternit\u00e9 des pages li\u00e9es\/associ\u00e9es. C&rsquo;est pourquoi il se distancie express\u00e9ment de tous les contenus des pages li\u00e9es\/associ\u00e9es qui ont \u00e9t\u00e9 modifi\u00e9es apr\u00e8s la cr\u00e9ation du lien. Cette constatation s&rsquo;applique \u00e0 tous les liens et r\u00e9f\u00e9rences plac\u00e9s dans l&rsquo;offre Internet de l&rsquo;auteur ainsi qu&rsquo;aux inscriptions de tiers dans les livres d&rsquo;or, forums de discussion, r\u00e9pertoires de liens, listes de diffusion et toutes autres formes de bases de donn\u00e9es cr\u00e9\u00e9es par l&rsquo;auteur et dont le contenu est accessible en \u00e9criture de l&rsquo;ext\u00e9rieur. Seul le fournisseur de la page \u00e0 laquelle il est fait r\u00e9f\u00e9rence est responsable des contenus ill\u00e9gaux, erron\u00e9s ou incomplets et en particulier des dommages r\u00e9sultant de l&rsquo;utilisation ou de la non-utilisation des informations ainsi pr\u00e9sent\u00e9es, et non celui qui ne fait que renvoyer \u00e0 la publication concern\u00e9e par le biais de liens.    <\/p>\n<p><strong>3. droit d&rsquo;auteur et droit des marques<\/strong><br \/>\nL&rsquo;auteur s&rsquo;efforce de respecter dans toutes les publications les droits d&rsquo;auteur des images, graphiques, documents sonores, s\u00e9quences vid\u00e9o et textes utilis\u00e9s, d&rsquo;utiliser des images, graphiques, documents sonores, s\u00e9quences vid\u00e9o et textes qu&rsquo;il a lui-m\u00eame cr\u00e9\u00e9s ou de recourir \u00e0 des graphiques, documents sonores, s\u00e9quences vid\u00e9o et textes libres de droits.<br \/>\nToutes les marques et marques d\u00e9pos\u00e9es mentionn\u00e9es dans l&rsquo;offre Internet et \u00e9ventuellement prot\u00e9g\u00e9es par des tiers sont soumises sans restriction aux dispositions du droit des marques en vigueur et aux droits de propri\u00e9t\u00e9 des propri\u00e9taires enregistr\u00e9s respectifs. La simple mention d&rsquo;une marque ne permet pas de conclure qu&rsquo;elle n&rsquo;est pas prot\u00e9g\u00e9e par les droits d&rsquo;un tiers !<br \/>\nLe copyright des objets publi\u00e9s et cr\u00e9\u00e9s par l&rsquo;auteur lui-m\u00eame reste la propri\u00e9t\u00e9 exclusive de l&rsquo;auteur des pages. Toute reproduction ou utilisation de tels graphiques, documents sonores, s\u00e9quences vid\u00e9o et textes dans d&rsquo;autres publications \u00e9lectroniques ou imprim\u00e9es est interdite sans l&rsquo;autorisation expresse de l&rsquo;auteur. <\/p>\n<p><strong>4. protection des donn\u00e9es<\/strong><br \/>\nDans la mesure o\u00f9 il est possible d&rsquo;entrer des donn\u00e9es personnelles ou professionnelles (adresses e-mail, noms, adresses) dans l&rsquo;offre Internet, la divulgation de ces donn\u00e9es par l&rsquo;utilisateur se fait sur une base express\u00e9ment volontaire. L&rsquo;utilisation et le paiement de tous les services propos\u00e9s sont autoris\u00e9s &#8211; dans la mesure o\u00f9 cela est techniquement possible et raisonnable &#8211; m\u00eame sans indication de telles donn\u00e9es ou en indiquant des donn\u00e9es anonymes ou un pseudonyme. L&rsquo;utilisation par des tiers des donn\u00e9es de contact publi\u00e9es dans le cadre des mentions l\u00e9gales ou d&rsquo;indications comparables, telles que les adresses postales, les num\u00e9ros de t\u00e9l\u00e9phone et de fax ainsi que les adresses e-mail, pour l&rsquo;envoi d&rsquo;informations non express\u00e9ment demand\u00e9es n&rsquo;est pas autoris\u00e9e. Nous nous r\u00e9servons express\u00e9ment le droit d&rsquo;engager des poursuites judiciaires contre les exp\u00e9diteurs de ce que l&rsquo;on appelle des spams en cas de non-respect de cette interdiction.   <\/p>\n<p><strong>5. validit\u00e9 juridique de cette clause de non-responsabilit\u00e9<\/strong><br \/>\nCette clause de non-responsabilit\u00e9 doit \u00eatre consid\u00e9r\u00e9e comme faisant partie de l&rsquo;offre Internet \u00e0 partir de laquelle il a \u00e9t\u00e9 fait r\u00e9f\u00e9rence \u00e0 cette page. Si des parties ou certaines formulations de ce texte ne devaient pas, plus ou pas enti\u00e8rement correspondre \u00e0 la situation juridique en vigueur, le contenu et la validit\u00e9 des autres parties du document n&rsquo;en seraient pas affect\u00e9s. <\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8890","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/pages\/8890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/comments?post=8890"}],"version-history":[{"count":12,"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/pages\/8890\/revisions"}],"predecessor-version":[{"id":12443,"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/pages\/8890\/revisions\/12443"}],"wp:attachment":[{"href":"https:\/\/bicyclejack.de\/fr\/wp-json\/wp\/v2\/media?parent=8890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}